{"id":27096,"date":"2025-02-25T16:42:33","date_gmt":"2025-02-25T16:42:33","guid":{"rendered":"https:\/\/albatrostextile.ee\/product\/fabric-ashley-wilde-bedgebury-peacock\/"},"modified":"2025-11-25T12:03:28","modified_gmt":"2025-11-25T12:03:28","slug":"fabric-ashley-wilde-bedgebury-peacock","status":"publish","type":"product","link":"https:\/\/albatrostextile.ee\/en\/product\/fabric-ashley-wilde-bedgebury-peacock\/","title":{"rendered":"Fabric  Ashley Wilde Bedgebury &#8211; Peacock"},"content":{"rendered":"<p style=\"margin-left:0px\">Ashley Wilde<\/p>\n<h2 style=\"margin-left:0px\">Bedgebury<\/h2>\n<figure class=\"table\" style=\"width:auto\">\n<table style=\"border:1px solid var(--theme-border-color)\">\n<tbody>\n<tr>\n<th style=\"border-bottom:1px solid var(--theme-border-color);border-left-width:0px;border-right:1px solid var(--theme-border-color);border-top-width:0px;padding:5.5px 30px 10px 0px;vertical-align:top\">Composition<\/th>\n<td style=\"border-bottom:1px solid var(--theme-border-color);border-left-width:0px;border-right:1px solid var(--theme-border-color);border-top-width:0px;padding:5.5px 5px 10px;vertical-align:top\">80% Recycled Polyester, 20% Polyester<\/td>\n<\/tr>\n<tr>\n<th style=\"border-bottom:1px solid var(--theme-border-color);border-left-width:0px;border-right:1px solid var(--theme-border-color);border-top-width:0px;padding:5.5px 30px 10px 0px;vertical-align:top\">Usage<\/th>\n<td style=\"border-bottom:1px solid var(--theme-border-color);border-left-width:0px;border-right:1px solid var(--theme-border-color);border-top-width:0px;padding:5.5px 5px 10px;vertical-align:top\">Drapes Only<\/td>\n<\/tr>\n<tr>\n<th style=\"border-bottom:1px solid var(--theme-border-color);border-left-width:0px;border-right:1px solid var(--theme-border-color);border-top-width:0px;padding:5.5px 30px 10px 0px;vertical-align:top\">Country of Origin<\/th>\n<td style=\"border-bottom:1px solid var(--theme-border-color);border-left-width:0px;border-right:1px solid var(--theme-border-color);border-top-width:0px;padding:5.5px 5px 10px;vertical-align:top\">Turkey<\/td>\n<\/tr>\n<tr>\n<th style=\"border-bottom:1px solid var(--theme-border-color);border-left-width:0px;border-right:1px solid var(--theme-border-color);border-top-width:0px;padding:5.5px 30px 10px 0px;vertical-align:top\">Style<\/th>\n<td style=\"border-bottom:1px solid var(--theme-border-color);border-left-width:0px;border-right:1px solid var(--theme-border-color);border-top-width:0px;padding:5.5px 5px 10px;vertical-align:top\">Conversational<\/td>\n<\/tr>\n<tr>\n<th style=\"border-bottom:1px solid var(--theme-border-color);border-left-width:0px;border-right:1px solid var(--theme-border-color);border-top-width:0px;padding:5.5px 30px 10px 0px;vertical-align:top\">Vertical Pattern Repeat<\/th>\n<td style=\"border-bottom:1px solid var(--theme-border-color);border-left-width:0px;border-right:1px solid var(--theme-border-color);border-top-width:0px;padding:5.5px 5px 10px;vertical-align:top\">37<\/td>\n<\/tr>\n<tr>\n<th style=\"border-bottom:1px solid var(--theme-border-color);border-left-width:0px;border-right:1px solid var(--theme-border-color);border-top-width:0px;padding:5.5px 30px 10px 0px;vertical-align:top\">Horizontal Pattern Repeat<\/th>\n<td style=\"border-bottom:1px solid var(--theme-border-color);border-left-width:0px;border-right:1px solid var(--theme-border-color);border-top-width:0px;padding:5.5px 5px 10px;vertical-align:top\">36<\/td>\n<\/tr>\n<tr>\n<th style=\"border-bottom:1px solid var(--theme-border-color);border-left-width:0px;border-right:1px solid var(--theme-border-color);border-top-width:0px;padding:5.5px 30px 10px 0px;vertical-align:top\">Width<\/th>\n<td style=\"border-bottom:1px solid var(--theme-border-color);border-left-width:0px;border-right:1px solid var(--theme-border-color);border-top-width:0px;padding:5.5px 5px 10px;vertical-align:top\">144<\/td>\n<\/tr>\n<tr>\n<th style=\"border-bottom:1px solid var(--theme-border-color);border-left-width:0px;border-right:1px solid var(--theme-border-color);border-top-width:0px;padding:5.5px 30px 10px 0px;vertical-align:top\">Grams Per Linear Meter<\/th>\n<td style=\"border-bottom:1px solid var(--theme-border-color);border-left-width:0px;border-right:1px solid var(--theme-border-color);border-top-width:0px;padding:5.5px 5px 10px;vertical-align:top\">432<\/td>\n<\/tr>\n<tr>\n<th style=\"border-bottom:1px solid var(--theme-border-color);border-left-width:0px;border-right:1px solid var(--theme-border-color);border-top-width:0px;padding:5.5px 30px 10px 0px;vertical-align:top\">Grams Per Sq Meter<\/th>\n<td style=\"border-bottom:1px solid var(--theme-border-color);border-left-width:0px;border-right:1px solid var(--theme-border-color);border-top-width:0px;padding:5.5px 5px 10px;vertical-align:top\">300<\/td>\n<\/tr>\n<tr>\n<th style=\"border-bottom:1px solid var(--theme-border-color);border-left-width:0px;border-right:1px solid var(--theme-border-color);border-top-width:0px;padding:5.5px 30px 10px 0px;vertical-align:top\">Commodity Code<\/th>\n<td style=\"border-bottom:1px solid var(--theme-border-color);border-left-width:0px;border-right:1px solid var(--theme-border-color);border-top-width:0px;padding:5.5px 5px 10px;vertical-align:top\">5407615000<\/td>\n<\/tr>\n<\/tbody>\n<\/table><figcaption>More Information<\/figcaption><\/figure>\n<p style=\"margin-left:0px\">Aftercare:<\/p>\n<ul>\n<li><img decoding=\"async\" class=\"image_resized\" style=\"width:39.3125px\" src=\"https:\/\/ashleywildegroup.com\/static\/version1713166557\/frontend\/Studioworx\/ashleywilde\/en_GB\/aftercare\/cw.jpg\" alt=\"CW\"><img decoding=\"async\" class=\"image_resized\" style=\"width:38.4px\" src=\"https:\/\/ashleywildegroup.com\/static\/version1713166557\/frontend\/Studioworx\/ashleywilde\/en_GB\/aftercare\/dnb.jpg\" alt=\"DNB\"><img decoding=\"async\" class=\"image_resized\" style=\"width:39.5px\" src=\"https:\/\/ashleywildegroup.com\/static\/version1713166557\/frontend\/Studioworx\/ashleywilde\/en_GB\/aftercare\/dnt.jpg\" alt=\"DNT\"><img decoding=\"async\" class=\"image_resized\" style=\"width:38.85px\" src=\"https:\/\/ashleywildegroup.com\/static\/version1713166557\/frontend\/Studioworx\/ashleywilde\/en_GB\/aftercare\/ir.jpg\" alt=\"IR\"><img decoding=\"async\" class=\"image_resized\" style=\"width:38.85px\" src=\"https:\/\/ashleywildegroup.com\/static\/version1713166557\/frontend\/Studioworx\/ashleywilde\/en_GB\/aftercare\/dcop.jpg\" alt=\"DCOP\"><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Ashley Wilde Bedgebury Composition 80% Recycled Polyester, 20% Polyester Usage Drapes Only Country of Origin Turkey Style Conversational Vertical Pattern Repeat 37 Horizontal Pattern Repeat 36 Width 144 Grams Per Linear Meter 432 Grams Per Sq Meter 300 Commodity Code 5407615000 More Information Aftercare:<\/p>\n","protected":false},"featured_media":27091,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[1348,1351],"product_tag":[],"class_list":["post-27096","product","type-product","status-publish","has-post-thumbnail","product_cat-textile","product_cat-textile-for-heavy-curtains","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fabric Ashley Wilde Bedgebury - Peacock - Albatros Textile<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/albatrostextile.ee\/en\/product\/fabric-ashley-wilde-bedgebury-peacock\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fabric Ashley Wilde Bedgebury - Peacock - Albatros Textile\" \/>\n<meta property=\"og:description\" content=\"Ashley Wilde Bedgebury Composition 80% Recycled Polyester, 20% Polyester Usage Drapes Only Country of Origin Turkey Style Conversational Vertical Pattern Repeat 37 Horizontal Pattern Repeat 36 Width 144 Grams Per Linear Meter 432 Grams Per Sq Meter 300 Commodity Code 5407615000 More Information Aftercare:\" \/>\n<meta property=\"og:url\" content=\"https:\/\/albatrostextile.ee\/en\/product\/fabric-ashley-wilde-bedgebury-peacock\/\" \/>\n<meta property=\"og:site_name\" content=\"Albatros Textile\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-25T12:03:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/albatrostextile.ee\/wp-content\/uploads\/2025\/02\/bedgeburype-1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/albatrostextile.ee\\\/en\\\/product\\\/fabric-ashley-wilde-bedgebury-peacock\\\/\",\"url\":\"https:\\\/\\\/albatrostextile.ee\\\/en\\\/product\\\/fabric-ashley-wilde-bedgebury-peacock\\\/\",\"name\":\"Fabric Ashley Wilde Bedgebury - Peacock - Albatros Textile\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/albatrostextile.ee\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/albatrostextile.ee\\\/en\\\/product\\\/fabric-ashley-wilde-bedgebury-peacock\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/albatrostextile.ee\\\/en\\\/product\\\/fabric-ashley-wilde-bedgebury-peacock\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/albatrostextile.ee\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/bedgeburype-1-1.jpg\",\"datePublished\":\"2025-02-25T16:42:33+00:00\",\"dateModified\":\"2025-11-25T12:03:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/albatrostextile.ee\\\/en\\\/product\\\/fabric-ashley-wilde-bedgebury-peacock\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/albatrostextile.ee\\\/en\\\/product\\\/fabric-ashley-wilde-bedgebury-peacock\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/albatrostextile.ee\\\/en\\\/product\\\/fabric-ashley-wilde-bedgebury-peacock\\\/#primaryimage\",\"url\":\"https:\\\/\\\/albatrostextile.ee\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/bedgeburype-1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/albatrostextile.ee\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/bedgeburype-1-1.jpg\",\"width\":700,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/albatrostextile.ee\\\/en\\\/product\\\/fabric-ashley-wilde-bedgebury-peacock\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/albatrostextile.ee\\\/en\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/albatrostextile.ee\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fabric Ashley Wilde Bedgebury &#8211; Peacock\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/albatrostextile.ee\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/albatrostextile.ee\\\/en\\\/\",\"name\":\"Albatros Textile\",\"description\":\"Viimsi kardinasalong\",\"publisher\":{\"@id\":\"https:\\\/\\\/albatrostextile.ee\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/albatrostextile.ee\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/albatrostextile.ee\\\/en\\\/#organization\",\"name\":\"Albatros Textile\",\"url\":\"https:\\\/\\\/albatrostextile.ee\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/albatrostextile.ee\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/albatrostextile.ee\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/cropped-albatros-textile-logo.png\",\"contentUrl\":\"https:\\\/\\\/albatrostextile.ee\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/cropped-albatros-textile-logo.png\",\"width\":512,\"height\":512,\"caption\":\"Albatros Textile\"},\"image\":{\"@id\":\"https:\\\/\\\/albatrostextile.ee\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/albatrostextile\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fabric Ashley Wilde Bedgebury - Peacock - Albatros Textile","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/albatrostextile.ee\/en\/product\/fabric-ashley-wilde-bedgebury-peacock\/","og_locale":"en_US","og_type":"article","og_title":"Fabric Ashley Wilde Bedgebury - Peacock - Albatros Textile","og_description":"Ashley Wilde Bedgebury Composition 80% Recycled Polyester, 20% Polyester Usage Drapes Only Country of Origin Turkey Style Conversational Vertical Pattern Repeat 37 Horizontal Pattern Repeat 36 Width 144 Grams Per Linear Meter 432 Grams Per Sq Meter 300 Commodity Code 5407615000 More Information Aftercare:","og_url":"https:\/\/albatrostextile.ee\/en\/product\/fabric-ashley-wilde-bedgebury-peacock\/","og_site_name":"Albatros Textile","article_modified_time":"2025-11-25T12:03:28+00:00","og_image":[{"width":700,"height":700,"url":"https:\/\/albatrostextile.ee\/wp-content\/uploads\/2025\/02\/bedgeburype-1-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/albatrostextile.ee\/en\/product\/fabric-ashley-wilde-bedgebury-peacock\/","url":"https:\/\/albatrostextile.ee\/en\/product\/fabric-ashley-wilde-bedgebury-peacock\/","name":"Fabric Ashley Wilde Bedgebury - Peacock - Albatros Textile","isPartOf":{"@id":"https:\/\/albatrostextile.ee\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/albatrostextile.ee\/en\/product\/fabric-ashley-wilde-bedgebury-peacock\/#primaryimage"},"image":{"@id":"https:\/\/albatrostextile.ee\/en\/product\/fabric-ashley-wilde-bedgebury-peacock\/#primaryimage"},"thumbnailUrl":"https:\/\/albatrostextile.ee\/wp-content\/uploads\/2025\/02\/bedgeburype-1-1.jpg","datePublished":"2025-02-25T16:42:33+00:00","dateModified":"2025-11-25T12:03:28+00:00","breadcrumb":{"@id":"https:\/\/albatrostextile.ee\/en\/product\/fabric-ashley-wilde-bedgebury-peacock\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/albatrostextile.ee\/en\/product\/fabric-ashley-wilde-bedgebury-peacock\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/albatrostextile.ee\/en\/product\/fabric-ashley-wilde-bedgebury-peacock\/#primaryimage","url":"https:\/\/albatrostextile.ee\/wp-content\/uploads\/2025\/02\/bedgeburype-1-1.jpg","contentUrl":"https:\/\/albatrostextile.ee\/wp-content\/uploads\/2025\/02\/bedgeburype-1-1.jpg","width":700,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/albatrostextile.ee\/en\/product\/fabric-ashley-wilde-bedgebury-peacock\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/albatrostextile.ee\/en\/homepage\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/albatrostextile.ee\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Fabric Ashley Wilde Bedgebury &#8211; Peacock"}]},{"@type":"WebSite","@id":"https:\/\/albatrostextile.ee\/en\/#website","url":"https:\/\/albatrostextile.ee\/en\/","name":"Albatros Textile","description":"Viimsi kardinasalong","publisher":{"@id":"https:\/\/albatrostextile.ee\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/albatrostextile.ee\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/albatrostextile.ee\/en\/#organization","name":"Albatros Textile","url":"https:\/\/albatrostextile.ee\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/albatrostextile.ee\/en\/#\/schema\/logo\/image\/","url":"https:\/\/albatrostextile.ee\/wp-content\/uploads\/2022\/11\/cropped-albatros-textile-logo.png","contentUrl":"https:\/\/albatrostextile.ee\/wp-content\/uploads\/2022\/11\/cropped-albatros-textile-logo.png","width":512,"height":512,"caption":"Albatros Textile"},"image":{"@id":"https:\/\/albatrostextile.ee\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/albatrostextile"]}]}},"_links":{"self":[{"href":"https:\/\/albatrostextile.ee\/en\/wp-json\/wp\/v2\/product\/27096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/albatrostextile.ee\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/albatrostextile.ee\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/albatrostextile.ee\/en\/wp-json\/wp\/v2\/comments?post=27096"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/albatrostextile.ee\/en\/wp-json\/wp\/v2\/media\/27091"}],"wp:attachment":[{"href":"https:\/\/albatrostextile.ee\/en\/wp-json\/wp\/v2\/media?parent=27096"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/albatrostextile.ee\/en\/wp-json\/wp\/v2\/product_brand?post=27096"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/albatrostextile.ee\/en\/wp-json\/wp\/v2\/product_cat?post=27096"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/albatrostextile.ee\/en\/wp-json\/wp\/v2\/product_tag?post=27096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}